{"id":501,"date":"2014-08-28T14:03:31","date_gmt":"2014-08-28T14:03:31","guid":{"rendered":"http:\/\/www.relatosxxx.net\/?p=501"},"modified":"2014-08-28T14:03:31","modified_gmt":"2014-08-28T14:03:31","slug":"adolescente-caliente","status":"publish","type":"post","link":"https:\/\/www.relatosxxx.net\/adolescente-caliente\/","title":{"rendered":"Adolescente caliente"},"content":{"rendered":"<p>Esto que voy a contarles sucedio hace unos a\u00f1os cuando tenia 12 a\u00f1os. Ya a esa edad me gustaba mucho masturbarme y tenia varias tecnicas para hacerlo. Apretaba fuerte la almohada y me movia hasta llegar al orgasmo o me apollaba en la vagina algun juguete que tubiera forma falica. Un dia fui a la casa de una amiga y juntas revisando los cajones de un tio de ella encontramos revistas pornograficas. Donde cojian por el culo y me encanto esa imagen, me calento de una manera que no me imaginaba que se podia.<br \/>\nEntonces desde ese dia comence a jugar con mi culo, le metia un dedo o dos y asi se fue agrandando; hasta que comence a meterme las dos piernas de la mu\u00f1eca articulada, lugo algun pepino que hubiera en casa. Me ponia crema de mi mama en el ojete y me mandaba un pepino gordo para adentro, siempre cudando que no se me fuera todo porque me daba mucho miedo. Pero me cojia el culo para masturbarme siempre.<br \/>\nCuando tenia 13 a\u00f1os me hice amiga de un vecino de 28 a\u00f1o que me veia como a una hemana menor, pero yo me masturbaba pensando en el, le tenia unas ganas locas.<br \/>\nUn dia el dormia la sieta con la ventana abierta (en verano) y yo estaba masturbandome como siempre con un pepino bien lubricado con crema, estaba re caliente y estaba aguantando las ganas de acabar entonces se me ocurrio meterme por la ventana en lo de mi querido vecino.<br \/>\nNo se que paso pero me le sente arriba, le saque las sabanas ( yo llevaba una pollera a tablas y no tenia bombacha) y empece a moverme arriba de el rozando su verga bien parada contra mi sexo, hacia adelante y hacia atras. a las tres o cuatro refregadas se me metio la verga en el culo que lo tenia tremendamente estirado; Tube un orgasmo increible. Y el no entendia que estaba pasando pero no recciono mal al contrario me lleno el culo de leche. Desde ese dia yo siempre iba a la siesta a coger el culo, la concha la mantuve virgen hasta que me case.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esto que voy a contarles sucedio hace unos a\u00f1os cuando tenia 12 a\u00f1os. Ya a esa edad me gustaba mucho masturbarme y tenia varias tecnicas para hacerlo. Apretaba fuerte la almohada y me movia hasta llegar al orgasmo o me apollaba en la vagina algun juguete que tubiera forma falica. Un dia fui a la casa de una amiga y juntas revisando los cajones de un tio de ella encontramos revistas pornograficas. Donde cojian por el culo y me encanto esa imagen, me calento de una manera que no me imaginaba que se podia. Entonces desde ese dia comence a <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[14],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Adolescente caliente - Relatosxxx.net<\/title>\n<meta name=\"description\" content=\"Esto que voy a contarles sucedio hace unos a\u00f1os cuando tenia 12 a\u00f1os. Ya a esa edad me gustaba mucho masturbarme y tenia varias tecnicas para hacerlo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.relatosxxx.net\/adolescente-caliente\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adolescente caliente - Relatosxxx.net\" \/>\n<meta property=\"og:description\" content=\"Esto que voy a contarles sucedio hace unos a\u00f1os cuando tenia 12 a\u00f1os. Ya a esa edad me gustaba mucho masturbarme y tenia varias tecnicas para hacerlo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.relatosxxx.net\/adolescente-caliente\/\" \/>\n<meta property=\"og:site_name\" content=\"Relatos XXX\" \/>\n<meta property=\"article:published_time\" content=\"2014-08-28T14:03:31+00:00\" \/>\n<meta name=\"author\" content=\"ElDuende\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ElDuende\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.relatosxxx.net\/adolescente-caliente\/\",\"url\":\"https:\/\/www.relatosxxx.net\/adolescente-caliente\/\",\"name\":\"Adolescente caliente - Relatosxxx.net\",\"isPartOf\":{\"@id\":\"https:\/\/www.relatosxxx.net\/#website\"},\"datePublished\":\"2014-08-28T14:03:31+00:00\",\"dateModified\":\"2014-08-28T14:03:31+00:00\",\"author\":{\"@id\":\"https:\/\/www.relatosxxx.net\/#\/schema\/person\/166efd26738b990dc38c86917bf0e00d\"},\"description\":\"Esto que voy a contarles sucedio hace unos a\u00f1os cuando tenia 12 a\u00f1os. Ya a esa edad me gustaba mucho masturbarme y tenia varias tecnicas para hacerlo.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.relatosxxx.net\/adolescente-caliente\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.relatosxxx.net\/adolescente-caliente\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.relatosxxx.net\/adolescente-caliente\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.relatosxxx.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adolescente caliente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.relatosxxx.net\/#website\",\"url\":\"https:\/\/www.relatosxxx.net\/\",\"name\":\"Relatos XXX\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.relatosxxx.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.relatosxxx.net\/#\/schema\/person\/166efd26738b990dc38c86917bf0e00d\",\"name\":\"ElDuende\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.relatosxxx.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2ab23d0e9e8f03addb8f1b409899fbf2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2ab23d0e9e8f03addb8f1b409899fbf2?s=96&d=mm&r=g\",\"caption\":\"ElDuende\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Adolescente caliente - Relatosxxx.net","description":"Esto que voy a contarles sucedio hace unos a\u00f1os cuando tenia 12 a\u00f1os. Ya a esa edad me gustaba mucho masturbarme y tenia varias tecnicas para hacerlo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.relatosxxx.net\/adolescente-caliente\/","og_locale":"es_ES","og_type":"article","og_title":"Adolescente caliente - Relatosxxx.net","og_description":"Esto que voy a contarles sucedio hace unos a\u00f1os cuando tenia 12 a\u00f1os. Ya a esa edad me gustaba mucho masturbarme y tenia varias tecnicas para hacerlo.","og_url":"https:\/\/www.relatosxxx.net\/adolescente-caliente\/","og_site_name":"Relatos XXX","article_published_time":"2014-08-28T14:03:31+00:00","author":"ElDuende","twitter_misc":{"Escrito por":"ElDuende","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.relatosxxx.net\/adolescente-caliente\/","url":"https:\/\/www.relatosxxx.net\/adolescente-caliente\/","name":"Adolescente caliente - Relatosxxx.net","isPartOf":{"@id":"https:\/\/www.relatosxxx.net\/#website"},"datePublished":"2014-08-28T14:03:31+00:00","dateModified":"2014-08-28T14:03:31+00:00","author":{"@id":"https:\/\/www.relatosxxx.net\/#\/schema\/person\/166efd26738b990dc38c86917bf0e00d"},"description":"Esto que voy a contarles sucedio hace unos a\u00f1os cuando tenia 12 a\u00f1os. Ya a esa edad me gustaba mucho masturbarme y tenia varias tecnicas para hacerlo.","breadcrumb":{"@id":"https:\/\/www.relatosxxx.net\/adolescente-caliente\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.relatosxxx.net\/adolescente-caliente\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.relatosxxx.net\/adolescente-caliente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.relatosxxx.net\/"},{"@type":"ListItem","position":2,"name":"Adolescente caliente"}]},{"@type":"WebSite","@id":"https:\/\/www.relatosxxx.net\/#website","url":"https:\/\/www.relatosxxx.net\/","name":"Relatos XXX","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.relatosxxx.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.relatosxxx.net\/#\/schema\/person\/166efd26738b990dc38c86917bf0e00d","name":"ElDuende","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.relatosxxx.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2ab23d0e9e8f03addb8f1b409899fbf2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2ab23d0e9e8f03addb8f1b409899fbf2?s=96&d=mm&r=g","caption":"ElDuende"}}]}},"_links":{"self":[{"href":"https:\/\/www.relatosxxx.net\/wp-json\/wp\/v2\/posts\/501"}],"collection":[{"href":"https:\/\/www.relatosxxx.net\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.relatosxxx.net\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.relatosxxx.net\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.relatosxxx.net\/wp-json\/wp\/v2\/comments?post=501"}],"version-history":[{"count":0,"href":"https:\/\/www.relatosxxx.net\/wp-json\/wp\/v2\/posts\/501\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.relatosxxx.net\/wp-json\/wp\/v2\/media?parent=501"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.relatosxxx.net\/wp-json\/wp\/v2\/categories?post=501"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.relatosxxx.net\/wp-json\/wp\/v2\/tags?post=501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}