{"id":979,"date":"2014-10-09T08:17:41","date_gmt":"2014-10-09T08:17:41","guid":{"rendered":"http:\/\/www.relatosxxx.net\/?p=979"},"modified":"2014-10-09T08:17:41","modified_gmt":"2014-10-09T08:17:41","slug":"el-mejor-descanso","status":"publish","type":"post","link":"https:\/\/www.relatosxxx.net\/el-mejor-descanso\/","title":{"rendered":"El mejor descanso"},"content":{"rendered":"<p>hola mi nombre es ricardo y ahora tengo 19 a\u00f1os, esta historia ocurrio cuando tenia 17 a\u00f1os de edad. No soy muy amante del deporte ni mucho menos del baloncesto pero ya habian llegado las vacaciones despues de un agetreado semestre en la escuela. Como es de costumbre cuando llega el verano todos cojemos esas vacaciones para descansar, hasta que llega un momento en que uno se aburre de estar en su casa, Asi que ese dia decidi salir a dar una vuelta por el barrio. ya eran las 2:30 de la tarde y el sol estaba picante y en todo su apogeo, fui un momento a un colmado que quedaba en las cercanias del lugar donde me encontraba. Entr\u00e9 y compre una botella de agua por que tenia una sed tremenda cuando fui a pagarla oi una voz conocida que me dijo: Oye, hace tiempo que no te veia por aqui!!! cuando me vire era mi mejor amigo pero que hace tiempo que no lo veia y nos saludamos; el estaba sudado y a primera vista se le podia notar su masculinidad, a mi nunca me atrajeron lo hombr! es pero en ese momento no se por que verlo todo sudado y con sus hombros musculosos al aire me exito bastante! a eso no le hize caso y le pregunte que hacia por alli y me dijo que estaba practicando el solo en una cancha de baloncesto que habia al lado del colmado por que el pertenecia a un equipo de baloncesto. Me pregunto que si queria jugar y yo por matar el aburrimiento pues accedi&#8230; yo no soy muy buen jugador del baloncesto pero intento. Fuimos a la cancha que es al aire libre y alli comenzamos a jugar. Luego de un buen rato de estar jugando yo gan\u00e9 el juego; pero estaba muy cansado y queria ba\u00f1arme y descansar un poco. La casa de Alex que es como se llama el queda cerca de mi casa razon por la cual le dije que me acompa\u00f1ara a mi casa y despues el siguiera hacia la suya y eso hicimos. En todo el transcurso del camino el iba un poco mas alfrente que yo asi que yo iba atras de el y eso me permitia ver completamente la forma de sus nalgas redonditas sobre el pantalon eso ta! mbien me excito y tampoco le hice caso. Al fin llegamos a mi casa el me pidio un poco de agua y entramos en mi casa no habia nada pues era de dia y mi madre trabaja. Le dije que cojiera el agua en lo que yo me ba\u00f1aba y dijo que no habia ningun problema. Me di un buen ba\u00f1o, pero se me habia olvidado traer la ropa que me iba a poner al ba\u00f1o asi que tuve que salir a mi cuarto en toalla el estaba en la sala. Cuando entre mi habitacion se me olvido cerrar la puerta con seguro y se me qued\u00f3 media abierta. Me puse un calzoncillo tipo bikini que son los que me gustan y sobre todo son muy buenos cuando hay calor. cuando estaba de espalda no me di cuenta que Alex habia entrado de repente lo oigo decir no se para que te molestas en ponerte ropa si esta con esta calor deberias estar desnudo!!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>hola mi nombre es ricardo y ahora tengo 19 a\u00f1os, esta historia ocurrio cuando tenia 17 a\u00f1os de edad. No soy muy amante del deporte ni mucho menos del baloncesto pero ya habian llegado las vacaciones despues de un agetreado semestre en la escuela. Como es de costumbre cuando llega el verano todos cojemos esas vacaciones para descansar, hasta que llega un momento en que uno se aburre de estar en su casa, Asi que ese dia decidi salir a dar una vuelta por el barrio. ya eran las 2:30 de la tarde y el sol estaba picante y en <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[14],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El mejor descanso - Relatosxxx.net<\/title>\n<meta name=\"description\" content=\"hola mi nombre es ricardo y ahora tengo 19 a\u00f1os, esta historia ocurrio cuando tenia 17 a\u00f1os de edad. No soy muy amante del deporte ni mucho menos del\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.relatosxxx.net\/el-mejor-descanso\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El mejor descanso - Relatosxxx.net\" \/>\n<meta property=\"og:description\" content=\"hola mi nombre es ricardo y ahora tengo 19 a\u00f1os, esta historia ocurrio cuando tenia 17 a\u00f1os de edad. No soy muy amante del deporte ni mucho menos del\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.relatosxxx.net\/el-mejor-descanso\/\" \/>\n<meta property=\"og:site_name\" content=\"Relatos XXX\" \/>\n<meta property=\"article:published_time\" content=\"2014-10-09T08:17:41+00:00\" \/>\n<meta name=\"author\" content=\"ElDuende\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ElDuende\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.relatosxxx.net\/el-mejor-descanso\/\",\"url\":\"https:\/\/www.relatosxxx.net\/el-mejor-descanso\/\",\"name\":\"El mejor descanso - Relatosxxx.net\",\"isPartOf\":{\"@id\":\"https:\/\/www.relatosxxx.net\/#website\"},\"datePublished\":\"2014-10-09T08:17:41+00:00\",\"dateModified\":\"2014-10-09T08:17:41+00:00\",\"author\":{\"@id\":\"https:\/\/www.relatosxxx.net\/#\/schema\/person\/166efd26738b990dc38c86917bf0e00d\"},\"description\":\"hola mi nombre es ricardo y ahora tengo 19 a\u00f1os, esta historia ocurrio cuando tenia 17 a\u00f1os de edad. No soy muy amante del deporte ni mucho menos del\",\"breadcrumb\":{\"@id\":\"https:\/\/www.relatosxxx.net\/el-mejor-descanso\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.relatosxxx.net\/el-mejor-descanso\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.relatosxxx.net\/el-mejor-descanso\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.relatosxxx.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El mejor descanso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.relatosxxx.net\/#website\",\"url\":\"https:\/\/www.relatosxxx.net\/\",\"name\":\"Relatos XXX\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.relatosxxx.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.relatosxxx.net\/#\/schema\/person\/166efd26738b990dc38c86917bf0e00d\",\"name\":\"ElDuende\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.relatosxxx.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2ab23d0e9e8f03addb8f1b409899fbf2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2ab23d0e9e8f03addb8f1b409899fbf2?s=96&d=mm&r=g\",\"caption\":\"ElDuende\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El mejor descanso - Relatosxxx.net","description":"hola mi nombre es ricardo y ahora tengo 19 a\u00f1os, esta historia ocurrio cuando tenia 17 a\u00f1os de edad. No soy muy amante del deporte ni mucho menos del","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.relatosxxx.net\/el-mejor-descanso\/","og_locale":"es_ES","og_type":"article","og_title":"El mejor descanso - Relatosxxx.net","og_description":"hola mi nombre es ricardo y ahora tengo 19 a\u00f1os, esta historia ocurrio cuando tenia 17 a\u00f1os de edad. No soy muy amante del deporte ni mucho menos del","og_url":"https:\/\/www.relatosxxx.net\/el-mejor-descanso\/","og_site_name":"Relatos XXX","article_published_time":"2014-10-09T08:17:41+00:00","author":"ElDuende","twitter_misc":{"Escrito por":"ElDuende","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.relatosxxx.net\/el-mejor-descanso\/","url":"https:\/\/www.relatosxxx.net\/el-mejor-descanso\/","name":"El mejor descanso - Relatosxxx.net","isPartOf":{"@id":"https:\/\/www.relatosxxx.net\/#website"},"datePublished":"2014-10-09T08:17:41+00:00","dateModified":"2014-10-09T08:17:41+00:00","author":{"@id":"https:\/\/www.relatosxxx.net\/#\/schema\/person\/166efd26738b990dc38c86917bf0e00d"},"description":"hola mi nombre es ricardo y ahora tengo 19 a\u00f1os, esta historia ocurrio cuando tenia 17 a\u00f1os de edad. No soy muy amante del deporte ni mucho menos del","breadcrumb":{"@id":"https:\/\/www.relatosxxx.net\/el-mejor-descanso\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.relatosxxx.net\/el-mejor-descanso\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.relatosxxx.net\/el-mejor-descanso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.relatosxxx.net\/"},{"@type":"ListItem","position":2,"name":"El mejor descanso"}]},{"@type":"WebSite","@id":"https:\/\/www.relatosxxx.net\/#website","url":"https:\/\/www.relatosxxx.net\/","name":"Relatos XXX","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.relatosxxx.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.relatosxxx.net\/#\/schema\/person\/166efd26738b990dc38c86917bf0e00d","name":"ElDuende","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.relatosxxx.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2ab23d0e9e8f03addb8f1b409899fbf2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2ab23d0e9e8f03addb8f1b409899fbf2?s=96&d=mm&r=g","caption":"ElDuende"}}]}},"_links":{"self":[{"href":"https:\/\/www.relatosxxx.net\/wp-json\/wp\/v2\/posts\/979"}],"collection":[{"href":"https:\/\/www.relatosxxx.net\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.relatosxxx.net\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.relatosxxx.net\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.relatosxxx.net\/wp-json\/wp\/v2\/comments?post=979"}],"version-history":[{"count":0,"href":"https:\/\/www.relatosxxx.net\/wp-json\/wp\/v2\/posts\/979\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.relatosxxx.net\/wp-json\/wp\/v2\/media?parent=979"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.relatosxxx.net\/wp-json\/wp\/v2\/categories?post=979"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.relatosxxx.net\/wp-json\/wp\/v2\/tags?post=979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}